{"id":231,"date":"2023-12-28T11:11:54","date_gmt":"2023-12-28T16:11:54","guid":{"rendered":"https:\/\/dfcint.ca\/?page_id=231"},"modified":"2023-12-28T11:18:21","modified_gmt":"2023-12-28T16:18:21","slug":"hifil","status":"publish","type":"page","link":"https:\/\/dfcint.ca\/index.php\/hifil\/","title":{"rendered":"Hif&#8217;il"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Hif&#8217;il Conjugations<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/dfcint.ca\/index.php\/hifil-perfect\/\" data-type=\"page\" data-id=\"132\">Perfect<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/dfcint.ca\/index.php\/hifil-imperfect\/\" data-type=\"page\" data-id=\"136\">Imperfect<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/dfcint.ca\/index.php\/hifil-narrative\/\" data-type=\"page\" data-id=\"139\">Narrative<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/dfcint.ca\/index.php\/hifil-participle\/\" data-type=\"page\" data-id=\"142\">Participle<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/dfcint.ca\/index.php\/hifil-infinitive-construct\/\" data-type=\"page\" data-id=\"145\">Infinitive Construct<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Hif&#8217;il Conjugations<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-231","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/dfcint.ca\/index.php\/wp-json\/wp\/v2\/pages\/231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dfcint.ca\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dfcint.ca\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dfcint.ca\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dfcint.ca\/index.php\/wp-json\/wp\/v2\/comments?post=231"}],"version-history":[{"count":2,"href":"https:\/\/dfcint.ca\/index.php\/wp-json\/wp\/v2\/pages\/231\/revisions"}],"predecessor-version":[{"id":240,"href":"https:\/\/dfcint.ca\/index.php\/wp-json\/wp\/v2\/pages\/231\/revisions\/240"}],"wp:attachment":[{"href":"https:\/\/dfcint.ca\/index.php\/wp-json\/wp\/v2\/media?parent=231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}